{"id":84,"count":1,"description":"","link":"https:\/\/sodiaal.coop\/en\/category\/new\/","name":"New","slug":"new","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New Archives | Sodiaal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sodiaal.coop\/en\/category\/new\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Archives | Sodiaal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sodiaal.coop\/en\/category\/new\/\" \/>\n<meta property=\"og:site_name\" content=\"Sodiaal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SodiaalCoop\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/category\\\/new\\\/\",\"url\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/category\\\/new\\\/\",\"name\":\"New Archives | Sodiaal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/category\\\/new\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/category\\\/new\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/\",\"name\":\"Sodiaal\",\"description\":\"Engag\u00e9s pour le meilleur des terroirs laitiers\",\"publisher\":{\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#organization\"},\"alternateName\":\"Coop\u00e9rative laiti\u00e8re fran\u00e7aise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#organization\",\"name\":\"Sodiaal\",\"alternateName\":\"Coop\u00e9rative laiti\u00e8re fran\u00e7aise\",\"url\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sodiaal.coop\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo_Sodiaal.svg\",\"contentUrl\":\"https:\\\/\\\/sodiaal.coop\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo_Sodiaal.svg\",\"width\":433,\"height\":194,\"caption\":\"Sodiaal\"},\"image\":{\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SodiaalCoop\\\/\",\"https:\\\/\\\/x.com\\\/SodiaalCoop\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sodiaal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@cooperativesodiaal3939\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Archives | Sodiaal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sodiaal.coop\/en\/category\/new\/","og_locale":"en_US","og_type":"article","og_title":"New Archives | Sodiaal","og_url":"https:\/\/sodiaal.coop\/en\/category\/new\/","og_site_name":"Sodiaal","twitter_card":"summary_large_image","twitter_site":"@SodiaalCoop","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sodiaal.coop\/en\/category\/new\/","url":"https:\/\/sodiaal.coop\/en\/category\/new\/","name":"New Archives | Sodiaal","isPartOf":{"@id":"https:\/\/sodiaal.coop\/en\/#website"},"breadcrumb":{"@id":"https:\/\/sodiaal.coop\/en\/category\/new\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/sodiaal.coop\/en\/category\/new\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sodiaal.coop\/en\/"},{"@type":"ListItem","position":2,"name":"New"}]},{"@type":"WebSite","@id":"https:\/\/sodiaal.coop\/en\/#website","url":"https:\/\/sodiaal.coop\/en\/","name":"Sodiaal","description":"Engag\u00e9s pour le meilleur des terroirs laitiers","publisher":{"@id":"https:\/\/sodiaal.coop\/en\/#organization"},"alternateName":"Coop\u00e9rative laiti\u00e8re fran\u00e7aise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sodiaal.coop\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sodiaal.coop\/en\/#organization","name":"Sodiaal","alternateName":"Coop\u00e9rative laiti\u00e8re fran\u00e7aise","url":"https:\/\/sodiaal.coop\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sodiaal.coop\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sodiaal.coop\/wp-content\/uploads\/2022\/10\/Logo_Sodiaal.svg","contentUrl":"https:\/\/sodiaal.coop\/wp-content\/uploads\/2022\/10\/Logo_Sodiaal.svg","width":433,"height":194,"caption":"Sodiaal"},"image":{"@id":"https:\/\/sodiaal.coop\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SodiaalCoop\/","https:\/\/x.com\/SodiaalCoop","https:\/\/www.linkedin.com\/company\/sodiaal\/","https:\/\/www.youtube.com\/@cooperativesodiaal3939"]}]}},"_links":{"self":[{"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/categories\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/posts?categories=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}