{"id":30798,"date":"2024-09-24T14:40:11","date_gmt":"2024-09-24T13:40:11","guid":{"rendered":"https:\/\/sodiaal.coop\/?page_id=30798"},"modified":"2026-06-04T16:11:30","modified_gmt":"2026-06-04T15:11:30","slug":"our-sustainability-initiative","status":"publish","type":"page","link":"https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/","title":{"rendered":"Our sustainability initiative"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-30798","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Our sustainability initiative | Sodiaal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our sustainability initiative | Sodiaal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/\" \/>\n<meta property=\"og:site_name\" content=\"Sodiaal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SodiaalCoop\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T15:11:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SodiaalCoop\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/our-sustainability-initiative\\\/\",\"url\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/our-sustainability-initiative\\\/\",\"name\":\"Our sustainability initiative | Sodiaal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#website\"},\"datePublished\":\"2024-09-24T13:40:11+00:00\",\"dateModified\":\"2026-06-04T15:11:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/our-sustainability-initiative\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sodiaal.coop\\\/en\\\/our-sustainability-initiative\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/our-sustainability-initiative\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our sustainability initiative\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/\",\"name\":\"Sodiaal\",\"description\":\"Engag\u00e9s pour le meilleur des terroirs laitiers\",\"publisher\":{\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#organization\"},\"alternateName\":\"Coop\u00e9rative laiti\u00e8re fran\u00e7aise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#organization\",\"name\":\"Sodiaal\",\"alternateName\":\"Coop\u00e9rative laiti\u00e8re fran\u00e7aise\",\"url\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sodiaal.coop\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo_Sodiaal.svg\",\"contentUrl\":\"https:\\\/\\\/sodiaal.coop\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo_Sodiaal.svg\",\"width\":433,\"height\":194,\"caption\":\"Sodiaal\"},\"image\":{\"@id\":\"https:\\\/\\\/sodiaal.coop\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SodiaalCoop\\\/\",\"https:\\\/\\\/x.com\\\/SodiaalCoop\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sodiaal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@cooperativesodiaal3939\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our sustainability initiative | Sodiaal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/","og_locale":"en_US","og_type":"article","og_title":"Our sustainability initiative | Sodiaal","og_url":"https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/","og_site_name":"Sodiaal","article_publisher":"https:\/\/www.facebook.com\/SodiaalCoop\/","article_modified_time":"2026-06-04T15:11:30+00:00","twitter_card":"summary_large_image","twitter_site":"@SodiaalCoop","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/","url":"https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/","name":"Our sustainability initiative | Sodiaal","isPartOf":{"@id":"https:\/\/sodiaal.coop\/en\/#website"},"datePublished":"2024-09-24T13:40:11+00:00","dateModified":"2026-06-04T15:11:30+00:00","breadcrumb":{"@id":"https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sodiaal.coop\/en\/our-sustainability-initiative\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sodiaal.coop\/en\/"},{"@type":"ListItem","position":2,"name":"Our sustainability initiative"}]},{"@type":"WebSite","@id":"https:\/\/sodiaal.coop\/en\/#website","url":"https:\/\/sodiaal.coop\/en\/","name":"Sodiaal","description":"Engag\u00e9s pour le meilleur des terroirs laitiers","publisher":{"@id":"https:\/\/sodiaal.coop\/en\/#organization"},"alternateName":"Coop\u00e9rative laiti\u00e8re fran\u00e7aise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sodiaal.coop\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sodiaal.coop\/en\/#organization","name":"Sodiaal","alternateName":"Coop\u00e9rative laiti\u00e8re fran\u00e7aise","url":"https:\/\/sodiaal.coop\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sodiaal.coop\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sodiaal.coop\/wp-content\/uploads\/2022\/10\/Logo_Sodiaal.svg","contentUrl":"https:\/\/sodiaal.coop\/wp-content\/uploads\/2022\/10\/Logo_Sodiaal.svg","width":433,"height":194,"caption":"Sodiaal"},"image":{"@id":"https:\/\/sodiaal.coop\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SodiaalCoop\/","https:\/\/x.com\/SodiaalCoop","https:\/\/www.linkedin.com\/company\/sodiaal\/","https:\/\/www.youtube.com\/@cooperativesodiaal3939"]}]}},"_links":{"self":[{"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/pages\/30798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/comments?post=30798"}],"version-history":[{"count":3,"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/pages\/30798\/revisions"}],"predecessor-version":[{"id":30997,"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/pages\/30798\/revisions\/30997"}],"wp:attachment":[{"href":"https:\/\/sodiaal.coop\/en\/wp-json\/wp\/v2\/media?parent=30798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}